{"id":3729,"date":"2020-05-04T08:39:47","date_gmt":"2020-05-04T08:39:47","guid":{"rendered":"https:\/\/vigorous-feistel.212-227-71-109.plesk.page\/?p=3729"},"modified":"2023-05-26T09:00:28","modified_gmt":"2023-05-26T09:00:28","slug":"pioggia-di-promozioni-per-i-clienti-interservice","status":"publish","type":"post","link":"https:\/\/interservice.tn.it\/en\/pioggia-di-promozioni-per-i-clienti-interservice\/","title":{"rendered":"PIOGGIA DI PROMOZIONI PER I CLIENTI INTERSERVICE!"},"content":{"rendered":"\n<p>Interservice S.p.A., l&#8217;officina multimarca&nbsp;per tutti i tipi di veicoli con assistenza 24h di propriet\u00e0 del&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.maurelligroup.com\/\" target=\"_blank\">Gruppo Maurelli<\/a>, ti ha riservato delle&nbsp;<a href=\"https:\/\/interservice.tn.it\/wp-content\/uploads\/2020\/09\/040520_promo_auto_van_interservice.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">speciali offerte<\/a>&nbsp;per la manutenzione della tua auto e\/o van che non potrai rifiutare!<\/p>\n\n\n\n<p>Interservice&nbsp;non \u00e8 soltanto un\u2019officina all\u2019avanguardia, dotata di strumenti moderni e personale&nbsp; specializzato; essa offre tutta una serie di servizi complementari, grazie alla sua avveniristica sede situata a Trento e alla sua appartenenza al&nbsp;<strong>Gruppo Maurelli<\/strong>, LEADER nel settore di ricambi per veicoli industriali.<br>Servizi che variano dall\u2019assistenza post vendita al servizio revisioni in sede, dalla sostituzione e riparazione pneumatici al servizio di lavatura che propone una gamma completa di portali di lavaggio e apparecchiature per la pulizia degli interni.<\/p>\n\n\n\n<p>Fino al 30 Giugno sono valide una serie di promozioni ghiottissime&#8230;<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/interservice.tn.it\/wp-content\/uploads\/2020\/09\/040520_promo_auto_van_interservice.pdf\">040520_promo_auto_van_interservice<\/a><a href=\"https:\/\/interservice.tn.it\/wp-content\/uploads\/2020\/09\/040520_promo_auto_van_interservice.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Interservice S.p.A., l&#8217;officina multimarca&nbsp;per tutti i tipi di veicoli con assistenza 24h di propriet\u00e0 del&nbsp;Gruppo Maurelli, ti ha riservato delle&nbsp;speciali offerte&nbsp;per la manutenzione della tua auto e\/o van che non potrai rifiutare! Interservice&nbsp;non \u00e8 soltanto un\u2019officina all\u2019avanguardia, dotata di strumenti moderni e personale&nbsp; specializzato; essa offre tutta una serie di servizi complementari, grazie alla sua [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":7462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"slim_seo":{"title":"PIOGGIA DI PROMOZIONI PER I CLIENTI INTERSERVICE! - Interservice","description":"Interservice S.p.A., l'officina multimarca&nbsp;per tutti i tipi di veicoli con assistenza 24h di propriet\u00e0 del&nbsp; Gruppo Maurelli , ti ha riservato delle&nb"},"footnotes":""},"categories":[63],"tags":[82,31,57,39,43,83,25],"class_list":["post-3729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-promozioni","tag-auto","tag-interservice","tag-officina","tag-promozione","tag-ricambi","tag-sanificazione","tag-trento"],"_links":{"self":[{"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/posts\/3729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/comments?post=3729"}],"version-history":[{"count":0,"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/posts\/3729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/media\/7462"}],"wp:attachment":[{"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/media?parent=3729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/categories?post=3729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interservice.tn.it\/en\/wp-json\/wp\/v2\/tags?post=3729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}